{"id":4344,"date":"2020-07-16T17:23:33","date_gmt":"2020-07-16T16:23:33","guid":{"rendered":"https:\/\/www.cerlesa.com\/?page_id=4344"},"modified":"2020-07-16T19:22:54","modified_gmt":"2020-07-16T18:22:54","slug":"bebidas-leonesas","status":"publish","type":"page","link":"https:\/\/www.cerlesa.com\/index.php\/bebidas-leonesas\/","title":{"rendered":"Bebidas Leonesas"},"content":{"rendered":"<p>[vc_row el_class=\u00bbquitamargenes\u00bb css=\u00bb.vc_custom_1455640788664{margin-bottom: 40px !important;}\u00bb][vc_column][rev_slider_vc alias=\u00bbbebidas\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbboxed\u00bb css=\u00bb.vc_custom_1455703767225{margin-top: 70px !important;}\u00bb][vc_column][vc_column_text el_class=\u00bbtrojo titulorayado\u00bb]BEBIDAS[\/vc_column_text][vc_row_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_column_text el_class=\u00bbtnegrita ttoggle\u00bb]BEBIDAS[\/vc_column_text][vc_toggle title=\u00bbLeche Lar\u00bb el_id=\u00bb1455627435136-4a8e9ab8-112e\u00bb]<\/p>\n<ul>\n<li>Leche especial de hosteler\u00eda<\/li>\n<li>Leche sin lactosa<\/li>\n<li>Leche semidesnatada<\/li>\n<li>Leche desnatada<\/li>\n<\/ul>\n<p>[\/vc_toggle][vc_toggle title=\u00bbAguas minerales\u00bb el_id=\u00bb1455627437523-3ba834b4-568f\u00bb]<\/p>\n<ul>\n<li>Piqueras<\/li>\n<li>Piqueras Premium<\/li>\n<\/ul>\n<p>[\/vc_toggle][vc_toggle title=\u00bbCarb\u00f3nicas\u00bb el_id=\u00bb1455627436464-8efdd362-4d09&#8243;]<\/p>\n<ul>\n<li>Gaseosa Piquera<\/li>\n<li>Butano Piquera<\/li>\n<\/ul>\n<p>[\/vc_toggle][vc_toggle title=\u00bbCervezas\u00bb el_id=\u00bb1455627463288-22343aaa-4679&#8243;]<\/p>\n<ul>\n<li>Nieve Rubia<\/li>\n<li>Nieve Tostada<\/li>\n<li>Nieve Radler<\/li>\n<\/ul>\n<p>[\/vc_toggle][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_column_text el_class=\u00bbtnegrita ttoggle\u00bb]VINOS Y CAVAS[\/vc_column_text][vc_toggle title=\u00bbVile\u00bb el_id=\u00bb1455639304487-3c0e2bb0-2d58&#8243;]<\/p>\n<ul>\n<li>Catedral de Le\u00f3n<\/li>\n<li>Real Arbas<\/li>\n<li>Valjunco<\/li>\n<li>Don Suero<\/li>\n<li>Vermut Picudo<\/li>\n<\/ul>\n<p>[\/vc_toggle][vc_toggle title=\u00bbValdoreo\u00bb el_id=\u00bb1455639305887-089e2416-e23c\u00bb]<\/p>\n<ul>\n<li>Mosto<\/li>\n<li>Vino de mesa<\/li>\n<\/ul>\n<p>[\/vc_toggle][vc_toggle title=\u00bbVinos Guerra\u00bb el_id=\u00bb1594476266796-1d20b0e7-8abc\u00bb]<\/p>\n<ul>\n<li>Armas de Guerra<\/li>\n<li>Se\u00f1or\u00edo del Bierzo<\/li>\n<li>Bliss<\/li>\n<li>Vermut<\/li>\n<\/ul>\n<p>[\/vc_toggle][vc_toggle title=\u00bbVinos de Valderas\u00bb el_id=\u00bb1594476269184-2c3ceca6-ce26&#8243;]<\/p>\n<ul>\n<li>Casto peque\u00f1o<\/li>\n<\/ul>\n<p>[\/vc_toggle][vc_toggle title=\u00bbVino D.O. Le\u00f3n\u00bb el_id=\u00bb1594476270561-dcd2fe02-1e45&#8243;]<\/p>\n<ul>\n<li>Jubileo<\/li>\n<li>Sensaciones<\/li>\n<\/ul>\n<p>[\/vc_toggle][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_column_text el_class=\u00bbtnegrita ttoggle\u00bb]LICORES[\/vc_column_text][vc_toggle title=\u00bbEspirituosos\u00bb el_id=\u00bb1455640047469-4920b09f-c9a2&#8243;]<\/p>\n<ul>\n<li>Ginebra 987<\/li>\n<\/ul>\n<p>[\/vc_toggle][vc_toggle title=\u00bbOrujos\u00bb el_id=\u00bb1455640048905-843f2edc-b7b7&#8243;]<\/p>\n<ul>\n<li>El Fauno<\/li>\n<\/ul>\n<p>[\/vc_toggle][vc_toggle title=\u00bbVermut Leon\u00e9s\u00bb el_id=\u00bb1456950679621-80ab1592-6286&#8243;]<\/p>\n<ul>\n<li>Picudo<\/li>\n<li>Guerra<\/li>\n<li>987<\/li>\n<li>Guzm\u00e1n<\/li>\n<\/ul>\n<p>[\/vc_toggle][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row el_class=\u00bbquitamargenes\u00bb css=\u00bb.vc_custom_1455640788664{margin-bottom: 40px !important;}\u00bb][vc_column][rev_slider_vc alias=\u00bbbebidas\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbboxed\u00bb css=\u00bb.vc_custom_1455703767225{margin-top: 70px !important;}\u00bb][vc_column][vc_column_text el_class=\u00bbtrojo titulorayado\u00bb]BEBIDAS[\/vc_column_text][vc_row_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_column_text el_class=\u00bbtnegrita ttoggle\u00bb]BEBIDAS[\/vc_column_text][vc_toggle title=\u00bbLeche Lar\u00bb el_id=\u00bb1455627435136-4a8e9ab8-112e\u00bb] Leche especial de hosteler\u00eda Leche sin lactosa Leche semidesnatada Leche desnatada [\/vc_toggle][vc_toggle title=\u00bbAguas minerales\u00bb el_id=\u00bb1455627437523-3ba834b4-568f\u00bb] Piqueras Piqueras Premium [\/vc_toggle][vc_toggle title=\u00bbCarb\u00f3nicas\u00bb el_id=\u00bb1455627436464-8efdd362-4d09&#8243;] Gaseosa Piquera Butano Piquera [\/vc_toggle][vc_toggle title=\u00bbCervezas\u00bb el_id=\u00bb1455627463288-22343aaa-4679&#8243;] Nieve Rubia Nieve Tostada Nieve Radler [\/vc_toggle][\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_column_text el_class=\u00bbtnegrita <\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full.php","meta":{"footnotes":""},"class_list":["post-4344","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.cerlesa.com\/index.php\/wp-json\/wp\/v2\/pages\/4344"}],"collection":[{"href":"https:\/\/www.cerlesa.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cerlesa.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cerlesa.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cerlesa.com\/index.php\/wp-json\/wp\/v2\/comments?post=4344"}],"version-history":[{"count":3,"href":"https:\/\/www.cerlesa.com\/index.php\/wp-json\/wp\/v2\/pages\/4344\/revisions"}],"predecessor-version":[{"id":4347,"href":"https:\/\/www.cerlesa.com\/index.php\/wp-json\/wp\/v2\/pages\/4344\/revisions\/4347"}],"wp:attachment":[{"href":"https:\/\/www.cerlesa.com\/index.php\/wp-json\/wp\/v2\/media?parent=4344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}